{"id":49351,"date":"2024-04-11T12:19:21","date_gmt":"2024-04-11T11:19:21","guid":{"rendered":"https:\/\/campax.org\/attivisti-che-cantano-ci-guarderemo-al-zurich-gv\/"},"modified":"2024-04-15T09:34:15","modified_gmt":"2024-04-15T08:34:15","slug":"attivisti-che-cantano-ci-guarderemo-al-zurich-gv","status":"publish","type":"post","link":"https:\/\/campax.org\/it\/attivisti-che-cantano-ci-guarderemo-al-zurich-gv\/","title":{"rendered":"Vittoria! Zurich esclude i nuovi giacimenti di petrolio e gas"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"49351\" class=\"elementor elementor-49351 elementor-49212\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-57b6e830 narrow elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"57b6e830\" data-element_type=\"section\" data-e-type=\"section\" id=\"page-title\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-231ed782\" data-id=\"231ed782\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-63f4d5e0 narrow  elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"63f4d5e0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-247f3160\" data-id=\"247f3160\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8956539 elementor-widget elementor-widget-post-info\" data-id=\"8956539\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-d3946a9\" itemprop=\"author\">\n\t\t\t\t\t\t<a href=\"https:\/\/campax.org\/it\/author\/admin\/\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-user-circle\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-author\">\n\t\t\t\t\t\t\t\t\t\tAdmin\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70c0bc85 elementor-widget elementor-widget-spacer\" data-id=\"70c0bc85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2617396b\" data-id=\"2617396b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36c73651 elementor-widget elementor-widget-post-info\" data-id=\"36c73651\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-98b305e\" itemprop=\"datePublished\">\n\t\t\t\t\t\t<a href=\"https:\/\/campax.org\/it\/2024\/04\/11\/\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-calendar\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t\t\t\t<time>Aprile 11, 2024<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2fc3b3fe narrow elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2fc3b3fe\" data-element_type=\"section\" data-e-type=\"section\" id=\"article-lead lead\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c3dbdbf\" data-id=\"c3dbdbf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3155d309 elementor-widget elementor-widget-text-editor\" data-id=\"3155d309\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Non ci credevo pi\u00f9. Ma ora \u00e8 successo: Zurich ha annunciato che non assicurer\u00e0 pi\u00f9 nuovi progetti petroliferi e di gas. Questo \u00e8 stato l&#8217;obiettivo principale della nostra campagna per tre anni. Ora lo abbiamo raggiunto. Questo dimostra che insieme possiamo raggiungere grandi obiettivi. Nora, grazie mille per il tuo sostegno!<\/b><br><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24965c98 narrow elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"24965c98\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8b03358\" data-id=\"8b03358\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3eca256a elementor-widget elementor-widget-text-editor\" data-id=\"3eca256a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Innanzitutto, le cose vanno diversamente da come si pensa. In realt\u00e0 ieri volevamo partecipare all&#8217;Assemblea generale di Zurich con 50 attivisti\/e e chiedere di non assicurare pi\u00f9 nuovi progetti petroliferi e di gas con decine di domande e un flash mob. <b>Per settimane sono stata impegnata a trovare un numero sufficiente di titoli azionari e a trasferire i diritti di voto<\/b> in modo da poter partecipare all&#8217;Assemblea generale con cos\u00ec tante persone.\u00a0<\/p><p>Ma gioved\u00ec scorso ho ricevuto <b>una telefonata da un giornalista<\/b>. Mi ha detto che Zurich stava pianificando nuove linee guida sul clima e non voleva pi\u00f9 assicurare nuovi progetti di estrazione di petrolio e gas e mi ha chiesto un commento. (1)<\/p><p>All&#8217;inizio non riuscivo a crederci. Solo dopo un po&#8217; ho capito la portata di questa telefonata. Questo uesto non \u00e8 solo <b>un passo importante per il clima e per il futuro di tutti\/e noi<\/b>. \u00c8 anche l&#8217;obiettivo principale della nostra campagna, che portiamo avanti da tre anni. Con innumerevoli campagne online e offline, abbiamo esercitato una pressione efficace su Zurigo e abbiamo <b>raggiunto insieme il nostro obiettivo<\/b>!\u00a0<\/p><p>Questo successo dimostra quanto siano importanti i nostri sforzi. Insieme possiamo raggiungere grandi obiettivi se perseveriamo.\u00a0<\/p><p><b>Purtroppo il nostro lavoro non \u00e8 ancora finito<\/b> con questo successo. Zurich non diventer\u00e0 un angelo con questo annuncio. In primo luogo, ha solo annunciato le nuove regole, ma non le ha ancora pubblicate; ci\u00f2 significa che alle parole devono seguire i fatti. In secondo luogo, le nuove regole presentano ancora importanti lacune. (2) <b>Zurich \u00e8 ancora lontana dall&#8217;armonizzare le sue attivit\u00e0 con l&#8217;obiettivo di limitare il riscaldamento globale a un massimo di 1,5 gradi<\/b>.\u00a0<\/p><p>Ci\u00f2 significa che la nostra campagna \u00e8 ancora necessaria. Non dobbiamo mollare ora, ma continuare a fare pressione su Zurich. Insieme possiamo fare in modo che Zurich mantenga le sue promesse e si ritiri completamente da carbone, petrolio e gas!<\/p><p><b>Ieri eravamo presenti all&#8217;Assemblea <\/b>generale per portare questo messaggio a Zurich. Insieme a 50 attivisti\/e, abbiamo detto chiaramente a Zurich: non molleremo finch\u00e9 non prenderanno una strada veramente rispettosa del clima!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ce30921 narrow elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ce30921\" data-element_type=\"section\" data-e-type=\"section\" id=\"video-lead\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-708a8229\" data-id=\"708a8229\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c40fced elementor-widget elementor-widget-video\" data-id=\"5c40fced\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe lazyload\" allowfullscreen allow=\"clipboard-write\" title=\"vimeo Video Player\" data-src=\"https:\/\/player.vimeo.com\/video\/933607370?color&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=1&amp;portrait=1&amp;byline=1#t=\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-load-mode=\"1\"><\/iframe>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-03c6125 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"03c6125\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42ddcf2\" data-id=\"42ddcf2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11fc11f elementor-widget elementor-widget-text-editor\" data-id=\"11fc11f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Note<\/p><p>(1) L&#8217;articolo \u00e8 stato pubblicato luned\u00ec. Abbiamo reagito immediatamente pubblicando un comunicato stampa che \u00e8 stato ripreso da diversi giornali. Vedi ad esempio https:\/\/www.finews.ch\/news\/versicherungen\/62124-zurich-versicherung-nachhaltigkeit-campax\u00a0 \u00a0<\/p><p>(2) Zurich si sta effettivamente ritirando dai nuovi giacimenti di petrolio e gas. Ma probabilmente continuer\u00e0 ad assicurare nuovi oleodotti e centrali elettriche. Continuer\u00e0 anche ad assicurare le attivit\u00e0 esistenti, anche se dovrebbe abbandonare rapidamente questa attivit\u00e0 se volesse affrontare seriamente un obiettivo credibile di 1,5 gradi.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Non ci credevo pi\u00f9. Ma ora \u00e8 successo: Zurich ha annunciato che non assicurer\u00e0 pi\u00f9 nuovi progetti petroliferi e di gas. Questo \u00e8 stato l&#8217;obiettivo principale della nostra campagna per tre anni. Ora lo abbiamo raggiunto. Questo dimostra che insieme possiamo raggiungere grandi obiettivi. Nora, grazie mille per il tuo sostegno! Innanzitutto, le cose vanno [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":49204,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[69,58],"tags":[],"class_list":["post-49351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clima-it","category-news-it"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-10-21 01:22:07","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/campax.org\/it\/wp-json\/wp\/v2\/posts\/49351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campax.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/campax.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/campax.org\/it\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/campax.org\/it\/wp-json\/wp\/v2\/comments?post=49351"}],"version-history":[{"count":0,"href":"https:\/\/campax.org\/it\/wp-json\/wp\/v2\/posts\/49351\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/campax.org\/it\/wp-json\/wp\/v2\/media\/49204"}],"wp:attachment":[{"href":"https:\/\/campax.org\/it\/wp-json\/wp\/v2\/media?parent=49351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/campax.org\/it\/wp-json\/wp\/v2\/categories?post=49351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/campax.org\/it\/wp-json\/wp\/v2\/tags?post=49351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}