{"id":70698,"date":"2025-12-09T15:22:28","date_gmt":"2025-12-09T14:22:28","guid":{"rendered":"https:\/\/campax.org\/staenderat-emailaktion-gewalt-an-frauen\/"},"modified":"2025-12-10T10:18:28","modified_gmt":"2025-12-10T09:18:28","slug":"staenderat-emailaktion-gewalt-an-frauen","status":"publish","type":"post","link":"https:\/\/campax.org\/fr\/staenderat-emailaktion-gewalt-an-frauen\/","title":{"rendered":"27 f\u00e9minicides \u2013 et pas d&rsquo;argent pour lutter contre la violence faite aux femmes ?!"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"70698\" class=\"elementor elementor-70698 elementor-70647\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9975c80 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9975c80\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-31ae8c3\" data-id=\"31ae8c3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a12a54 elementor-widget elementor-widget-heading\" data-id=\"0a12a54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">27 f\u00e9minicides \u2013 et pas d'argent pour lutter contre la violence faite aux femmes ?!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52a0526 elementor-widget elementor-widget-text-editor\" data-id=\"52a0526\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><span style=\"text-decoration: underline;\">Nous avons gagn\u00e9 !<\/span> Merci pour votre engagement ! Pr\u00e8s de 1 200 mails ont \u00e9t\u00e9 envoy\u00e9s hier aux membres du Conseil des \u00c9tats et la pression a port\u00e9 ses fruits.<\/strong><\/p><p><br \/><strong>Le Conseil des \u00c9tats a approuv\u00e9 l&rsquo;augmentation des fonds allou\u00e9s \u00e0 la protection des femmes.<\/strong><\/p><p><br \/><strong>Nous poursuivons nos efforts.\ud83d\udc9c<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5977f2c elementor-widget elementor-widget-text-editor\" data-id=\"5977f2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Hier<\/strong> soir, lundi 8 d\u00e9cembre, <strong>le Conseil national a d\u00e9cid\u00e9 de ne pas allouer de fonds suppl\u00e9mentaires \u00e0 la mise en \u0153uvre de la Convention d&rsquo;Istanbul et \u00e0 la lutte contre la violence.<\/strong><\/p><p>\u00a0<\/p><p><strong>27 f\u00e9minicides ont d\u00e9j\u00e0 \u00e9t\u00e9 commis cette ann\u00e9e<\/strong>, ce qui montre la n\u00e9cessit\u00e9 dramatique de lutter r\u00e9solument contre la violence bas\u00e9e sur le genre. La d\u00e9cision prise hier par le Conseil national contraste fortement avec cette n\u00e9cessit\u00e9.<\/p><p>\u00a0<\/p><p><strong>C&rsquo;est un coup dur pour toutes les personnes concern\u00e9es<\/strong>, que nous ne pouvons pas laisser passer !<\/p><p>\u00a0<\/p><p><strong>Votre voix compte, maintenant :<\/strong><br \/>Demain (mercredi), la question sera renvoy\u00e9e au Conseil des \u00c9tats. Lui seul peut corriger cette d\u00e9cision irresponsable et sauver les fonds indispensables \u00e0 la pr\u00e9vention, \u00e0 la protection et \u00e0 l&rsquo;aide aux victimes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-463f5c5 elementor-widget elementor-widget-text-editor\" data-id=\"463f5c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Aidez-nous d\u00e8s maintenant ! Envoyez un mail pr\u00e9-r\u00e9dig\u00e9 aux membres du Conseil des \u00c9tats qui ont vot\u00e9 contre (ou pour) les fonds destin\u00e9s \u00e0 la lutte contre la violence bas\u00e9e sur le genre.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49eb3a3 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"49eb3a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-hands-helping\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12ff889 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"12ff889\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b6841d5\" data-id=\"b6841d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36ae3a3 elementor-widget elementor-widget-heading\" data-id=\"36ae3a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Faire changer d'avis les membres de droite et du centre-droit du Conseil des \u00c9tats<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75fe2e4 elementor-widget elementor-widget-text-editor\" data-id=\"75fe2e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Ce mail est adress\u00e9 aux membres du Conseil des \u00c9tats qui ont vot\u00e9 <span style=\"text-decoration: underline;\">contre<\/span> l&rsquo;octroi d&rsquo;un million de francs suisses pour la mise en \u0153uvre de la Convention d&rsquo;Istanbul.<\/strong><\/p><p><br \/>Nous devons les convaincre que la violence \u00e0 l&rsquo;\u00e9gard des femmes est un sujet qui nous concerne touxtes. Pour cela, il faut de toute urgence des fonds et leur voix pour la mise en \u0153uvre de la Convention d&rsquo;Istanbul.<\/p><p><br \/>Lorsque vous cliquez sur le bouton, votre programme de messagerie s&rsquo;ouvre.<\/p><p><br \/>Vous pouvez alors modifier le texte pr\u00e9-r\u00e9dig\u00e9 si vous le souhaitez.<\/p><p><br \/>Entrez ensuite votre propre objet et signez le mail avec votre nom.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a31ce1 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"8a31ce1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm elementor-animation-grow\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\ud83d\udd25Campagne par e-mail d\u00e9sactiv\u00e9e\ud83d\udd25<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3973450 elementor-widget elementor-widget-text-editor\" data-id=\"3973450\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si le bouton ne fonctionne pas, voici notre texte pr\u00e9-r\u00e9dig\u00e9 et les adresses e-mail :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db954a2 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"db954a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Destinataires :<\/strong> bischof@law-firm.ch, severin.bruengger@parl.ch, thierry.burkart@parl.ch, andrea.caroni@parl.ch, marco.chiesa@parl.ch, josef.dittli@parl.ch, daniel.faessler@parl.ch, info@esther-friedli.ch, hannes.germann@parl.ch, andrea.gmuer-schoenenberger@parl.ch, petra.goessi@parl.ch, mail@benjamin-muehlemann.ch, damian.mueller@parl.ch, mauro.poggia@parl.ch, fabio.regazzi@parl.ch, werner.salzmann@parl.ch, martin.schmid@kunzschmid.ch, pirmin.schwander@parl.ch, info@jakob-stark.ch, hans.wicki@parl.ch, benedikt.wuerth@swisslegal.ch<\/p><p>\u00a0<\/p><p><strong>BCC:<\/strong><\/p><p>info@campax.org (afin que nous puissions compter le nombre de mails envoy\u00e9s)<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bb3003 elementor-widget elementor-widget-text-editor\" data-id=\"3bb3003\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Proposition de texte (\u00e0 copier) :<\/strong><br \/>Mesdames et Messieurs les membres du Conseil des \u00c9tats,<\/p><p>\u00a0<\/p><p>C&rsquo;est avec inqui\u00e9tude que j&rsquo;ai appris que le Conseil national avait rejet\u00e9 les fonds pr\u00e9vus pour la mise en \u0153uvre de la Convention d&rsquo;Istanbul. Une d\u00e9cision que vous avez soutenue. Compte tenu des 27 f\u00e9minicides commis au cours de cette seule ann\u00e9e et des dizaines de milliers de cas de violence domestique, je vous demande de reconsid\u00e9rer la port\u00e9e de cette d\u00e9cision.<\/p><p><br \/>Nous savons que la pr\u00e9vention, les offres de protection, les maisons d&rsquo;accueil pour femmes, les services sp\u00e9cialis\u00e9s et les campagnes de sensibilisation ne peuvent fonctionner de mani\u00e8re fiable que s&rsquo;ils sont suffisamment financ\u00e9s. Une r\u00e9duction de ces fonds signifie moins de s\u00e9curit\u00e9 pour les personnes concern\u00e9es et emp\u00eache de d\u00e9tecter et d&rsquo;arr\u00eater la violence \u00e0 un stade pr\u00e9coce.<\/p><p><br \/>La Suisse s&rsquo;est engag\u00e9e juridiquement et moralement \u00e0 prot\u00e9ger efficacement les femmes et les personnes victimes de violence domestique. Renoncer aux moyens n\u00e9cessaires est contraire \u00e0 la Convention d&rsquo;Istanbul et aux objectifs du plan d&rsquo;action national. Je suis convaincue que cette responsabilit\u00e9 occupe \u00e9galement une place importante dans votre syst\u00e8me de valeurs personnel.<\/p><p><br \/>Je vous demande donc instamment de corriger la d\u00e9cision du Conseil national et de voter en faveur du r\u00e9tablissement des fonds. La protection contre la violence n&rsquo;est pas une option, mais notre devoir !<\/p><p><br \/>Avec mes salutations distingu\u00e9es<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-14a7e7c\" data-id=\"14a7e7c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5983230 elementor-widget elementor-widget-heading\" data-id=\"5983230\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Encourager les membres du Conseil des \u00c9tats \u00e0 se rallier \u00e0 notre cause<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba39f1e elementor-widget elementor-widget-text-editor\" data-id=\"ba39f1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Ce mail est adress\u00e9 aux membres du Conseil des \u00c9tats qui ont vot\u00e9 <span style=\"text-decoration: underline;\">en faveur<\/span> de l&rsquo;octroi d&rsquo;un million de francs suisses pour la mise en \u0153uvre de la Convention d&rsquo;Istanbul.<\/strong><\/p><p><br \/>Il s&rsquo;agit d&rsquo;une \u00e9tape extr\u00eamement importante (m\u00eame si ce million est largement insuffisant, au vu des 27 f\u00e9minicides commis cette ann\u00e9e).<br \/>Nous devons les encourager \u00e0 voter \u00e0 nouveau en faveur de ces fonds !<\/p><p><br \/>Lorsque vous cliquez sur le bouton, votre programme de messagerie s&rsquo;ouvre.<\/p><p><br \/>Vous pouvez modifier le texte pr\u00e9-r\u00e9dig\u00e9 si vous le souhaitez.<\/p><p>Entrez ensuite votre propre objet et signez l&rsquo;e-mail avec votre nom.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3775a6e elementor-align-left elementor-widget elementor-widget-button\" data-id=\"3775a6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm elementor-animation-grow\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\ud83d\udc9c Campagne par e-mail d\u00e9sactiv\u00e9e \ud83d\udc9c<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af9d212 elementor-widget elementor-widget-text-editor\" data-id=\"af9d212\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si le bouton ne fonctionne pas, voici notre texte pr\u00e9-r\u00e9dig\u00e9 et les adresses e-mail :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b18bd00 elementor-widget elementor-widget-text-editor\" data-id=\"b18bd00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Destinataires :<\/strong> marianne.binder-keller@parl.ch, pascal.broulis@parl.ch, contact@isabellechassot.ch, mathilde.crevoisier@parl.ch, erich.ettlin@parl.ch, fabien.fivaz@parl.ch, johanna.gapany@parl.ch, kontakt@mayagraf.ch, brigitte.haeberli@parl.ch, peter.hegglin@parl.ch, eva.herzog@parl.ch, baptiste.hurni@parl.ch, jositsch@ius.uzh.ch, charles.juillard@parl.ch, pierre-yves.maillard@parl.ch, marianne.maret@parl.ch, mail@matthiasmichel.ch, tiana.moser@parl.ch, beat.rieder@parl.ch, mail@franziskaroth.ch, carlo.sommaruga@parl.ch, flavia.wasserfallen@parl.ch, heidi.zgraggen@parl.ch, info@mathiaszopfi.ch<\/p><p>\u00a0<\/p><p><strong>BCC:<\/strong><\/p><p>info@campax.org (afin que nous puissions compter le nombre de mails envoy\u00e9s)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d73e4a4 elementor-widget elementor-widget-text-editor\" data-id=\"d73e4a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Proposition de texte (\u00e0 copier) :<\/strong><br \/>Mesdames et Messieurs les membres du Conseil des \u00c9tats,<\/p><p>\u00a0<\/p><p>Je tiens \u00e0 vous remercier sinc\u00e8rement de vous \u00eatre engag\u00e9\u00b7e\u00b7s, dans le cadre du d\u00e9bat sur le budget, en faveur de l&rsquo;octroi des fonds n\u00e9cessaires \u00e0 la mise en \u0153uvre de la Convention d&rsquo;Istanbul. Votre d\u00e9cision est un signal fort et important pour la protection contre la violence sexiste et domestique et pour toutes les personnes qui d\u00e9pendent de structures de soutien efficaces.<\/p><p>\u00a0<\/p><p>Compte tenu des 27 f\u00e9minicides commis cette ann\u00e9e seulement et des dizaines de milliers de cas de violence domestique, votre engagement est inestimable. Le travail de pr\u00e9vention, les maisons d&rsquo;accueil pour femmes, les centres sp\u00e9cialis\u00e9s et les mesures de sensibilisation ne peuvent \u00eatre efficaces que s&rsquo;ils b\u00e9n\u00e9ficient d&rsquo;un financement fiable. Votre engagement montre que vous reconnaissez l&rsquo;urgence et la responsabilit\u00e9 de la situation.<\/p><p><br \/>Je vous demande de continuer \u00e0 renforcer cette position. La d\u00e9cision du Conseil national de supprimer les fonds suppl\u00e9mentaires met en p\u00e9ril des mesures de protection essentielles et est contraire aux obligations de la Suisse en vertu du droit international. J&rsquo;esp\u00e8re vivement que vous vous engagerez \u00e0 nouveau pour que les fonds n\u00e9cessaires soient allou\u00e9s, afin de prot\u00e9ger les personnes concern\u00e9es et de respecter les droits humains.<\/p><p>\u00a0<\/p><p>Merci beaucoup pour votre engagement !<\/p><p><br \/>Avec mes meilleures salutations<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>27 f\u00e9minicides \u2013 et pas d&rsquo;argent pour lutter contre la violence faite aux femmes ?! Nous avons gagn\u00e9 ! Merci pour votre engagement ! Pr\u00e8s de 1 200 mails ont \u00e9t\u00e9 envoy\u00e9s hier aux membres du Conseil des \u00c9tats et la pression a port\u00e9 ses fruits. Le Conseil des \u00c9tats a approuv\u00e9 l&rsquo;augmentation des fonds [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[127,63,74],"tags":[],"class_list":["post-70698","post","type-post","status-publish","format-standard","hentry","category-action-fr","category-campax-fr","category-egalite"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-10-21 07:46:21","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/campax.org\/fr\/wp-json\/wp\/v2\/posts\/70698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campax.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/campax.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/campax.org\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/campax.org\/fr\/wp-json\/wp\/v2\/comments?post=70698"}],"version-history":[{"count":11,"href":"https:\/\/campax.org\/fr\/wp-json\/wp\/v2\/posts\/70698\/revisions"}],"predecessor-version":[{"id":70723,"href":"https:\/\/campax.org\/fr\/wp-json\/wp\/v2\/posts\/70698\/revisions\/70723"}],"wp:attachment":[{"href":"https:\/\/campax.org\/fr\/wp-json\/wp\/v2\/media?parent=70698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/campax.org\/fr\/wp-json\/wp\/v2\/categories?post=70698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/campax.org\/fr\/wp-json\/wp\/v2\/tags?post=70698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}