{"id":59082,"date":"2024-12-13T10:05:50","date_gmt":"2024-12-13T09:05:50","guid":{"rendered":"https:\/\/campax.org\/?p=59082"},"modified":"2024-12-13T10:44:24","modified_gmt":"2024-12-13T09:44:24","slug":"zusammenfassung-der-kampagne-faire-arbeitsbedingungen-bei-dpd","status":"publish","type":"post","link":"https:\/\/campax.org\/de\/zusammenfassung-der-kampagne-faire-arbeitsbedingungen-bei-dpd\/","title":{"rendered":"Zusammenfassung der Kampagne: Faire Arbeitsbedingungen bei DPD"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"59082\" class=\"elementor elementor-59082\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3804e66e narrow elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3804e66e\" data-element_type=\"section\" data-e-type=\"section\" id=\"page-title\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fa6c854\" data-id=\"fa6c854\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-776e772 elementor-widget elementor-widget-spacer\" data-id=\"776e772\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d42f46 elementor-widget elementor-widget-image\" data-id=\"3d42f46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"725\" height=\"300\" data-src=\"https:\/\/campax.org\/wp-content\/uploads\/2024\/12\/3-2.png\" class=\"attachment-large size-large wp-image-59085 lazyload\" alt=\"DPD: Stopp die Subunternehmer\" data-srcset=\"https:\/\/campax.org\/wp-content\/uploads\/2024\/12\/3-2.png 725w, https:\/\/campax.org\/wp-content\/uploads\/2024\/12\/3-2-300x124.png 300w\" data-sizes=\"(max-width: 725px) 100vw, 725px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 725px; --smush-placeholder-aspect-ratio: 725\/300;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a4d779 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a4d779\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-08a3b7c\" data-id=\"08a3b7c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-71cbafc9 narrow  elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"71cbafc9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-49c13b42\" data-id=\"49c13b42\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c16950c elementor-widget elementor-widget-post-info\" data-id=\"3c16950c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-d3946a9\" itemprop=\"author\">\n\t\t\t\t\t\t<a href=\"https:\/\/campax.org\/de\/author\/iared\/\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-user-circle\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-author\">\n\t\t\t\t\t\t\t\t\t\tJared Camponovo\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2472e19 elementor-widget elementor-widget-spacer\" data-id=\"2472e19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-81fca40\" data-id=\"81fca40\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f4fee10 elementor-widget elementor-widget-post-info\" data-id=\"3f4fee10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-98b305e\" itemprop=\"datePublished\">\n\t\t\t\t\t\t<a href=\"https:\/\/campax.org\/de\/2024\/12\/13\/\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-calendar\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t\t\t\t<time>Dezember 13, 2024<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3759fe77 narrow elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3759fe77\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-271a2ca7\" data-id=\"271a2ca7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37eb96b elementor-widget elementor-widget-spacer\" data-id=\"37eb96b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-241f3b62 elementor-widget elementor-widget-text-editor\" data-id=\"241f3b62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); font-size: 1rem;\">Die Kampagne f\u00fcr faire Arbeitsbedingungen bei DPD begann mit einem ersch\u00fctternden Bericht des Schweizer Fernsehens (SRF). Der Artikel deckte auf, dass die Arbeitsbedingungen f\u00fcr viele Fahrer*innen bei DPD miserabel sind. Extreme Arbeitszeiten, unzumutbare Lasten und die fehlende direkte Anstellung bei DPD selbst machen die Situation f\u00fcr viele untragbar. Stattdessen l\u00e4sst das Unternehmen Zusteller*innen \u00fcber Subunternehmer arbeiten, was Unsicherheit und oft auch Verst\u00f6\u00dfe gegen Arbeitsgesetze nach sich zieht.<\/span><\/p><div>\u00a0<\/div><div><strong>Schnell reagiert: Petition f\u00fcr bessere Arbeitsbedingungen<\/strong><\/div><div>Als Reaktion auf die Enth\u00fcllungen haben wir in Windeseile eine\u00a0<a href=\"https:\/\/act.campax.org\/petitions\/dpd-stoppt-die-subunternehmen-faire-anstellung-jetzt\" target=\"_blank\" rel=\"noopener noreferrer\">Petition<\/a>\u00a0gestartet, die klare Forderungen an DPD Schweiz stellt:<\/div><div>\u00a0<\/div><ul><li>Direkte Anstellung aller DPD-Fahrer*innen bei DPD Schweiz und die Beendigung der Zusammenarbeit mit Subunternehmen.<\/li><li>Die Sicherstellung von fairen Arbeitsbedingungen: Weniger Zeitdruck, k\u00fcrzere Arbeitstage, eine saubere Zeiterfassung und angemessene Pausen.<\/li><li>Sicherstellung eines existenzsichernden Lohns f\u00fcr alle Besch\u00e4ftigten.<\/li><li>Abschaffung des Strafpunktesystems, das Druck aus\u00fcbt und finanzielle Belastungen auf die Fahrer*innen abw\u00e4lzt.<\/li><li>Bereitstellung sicherer und gesetzeskonformer Arbeitsmittel und Fahrzeuge, die den gesundheitlichen Anforderungen der Fahrer*innen entsprechen.<\/li><li>Ein Ende von \u00fcberladenen Fahrzeugen, Installierung von Fahrzeugwaagen in allen Logistikstandorten.<\/li><li>Respekt der Gewerkschaftsrechte der Besch\u00e4ftigten<\/li><\/ul><div>\u00a0<\/div><div><strong>Die Petition und E-Mail Aktion<\/strong><\/div><div>Die Petition fand in unserer Community rasch Unterst\u00fctzung. Wir haben sie \u00fcber unsere Netzwerke und Kan\u00e4le verbreitet, um so viele Menschen wie m\u00f6glich zu erreichen. Dar\u00fcber hinaus haben wir eine\u00a0<a href=\"https:\/\/campax.org\/dpd-skandal\/\" target=\"_blank\" rel=\"noopener noreferrer\">E-Mail-Aktionsseite<\/a>\u00a0eingerichtet, auf der Unterst\u00fctzer*innen dem CEO von DPD direkt schreiben konnten, um die Forderungen der Petition zu bekr\u00e4ftigen. Dieser Aufruf wurde aktiv von \u00fcber 200 Unterzeichner*innen wahrgenommen.<\/div><div>\u00a0<\/div><div><strong>Vergeblicher Versuch: Kontaktaufnahme mit DPD<\/strong><\/div><div>Nachdem wir \u00fcber 3\u2019000 Unterschriften gesammelt hatten, kontaktierten wir das Unternehmen, um die Petition pers\u00f6nlich an den CEO, Herrn Tilmann Schultze, zu \u00fcbergeben. Trotz mehrfacher Versuche war er offenbar nicht bereit, die Unterschriften entgegenzunehmen. Stattdessen antwortete der Marketing &amp; Customer Experience Director von DPD, dass das Unternehmen keine Gelegenheit gehabt habe, auf die Vorw\u00fcrfe des SRF zu reagieren und dass die Berichte nicht der Wahrheit entspr\u00e4chen.<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7a16b1b1 narrow elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7a16b1b1\" data-element_type=\"section\" data-e-type=\"section\" id=\"video-lead\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-144fc9ee\" data-id=\"144fc9ee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-639a3813 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"639a3813\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-318400f7 elementor-widget elementor-widget-video\" data-id=\"318400f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe lazyload\" allowfullscreen allow=\"clipboard-write\" title=\"vimeo Video Player\" data-src=\"https:\/\/player.vimeo.com\/video\/1038208284?color&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=1&amp;portrait=1&amp;byline=1#t=\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-load-mode=\"1\"><\/iframe>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cf7888 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6cf7888\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2172c09 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2172c09\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a854cc\" data-id=\"3a854cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c27ef47 elementor-widget elementor-widget-text-editor\" data-id=\"c27ef47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><strong>Die Fakten: SRF widerspricht DPD<\/strong><\/div><div>Die Medienstelle des SRF stellt klar: Die Vorw\u00fcrfe von DPD Schweiz weisen wir zur\u00fcck. \u00abSRF Investigativ\u00bb bat mehrmals um ein Interview vor der Kamera mit CEO Tilmann Schultze oder einer anderen verantwortlichen Person von DPD Schweiz. Die erste Interviewanfrage erhielt DPD Schweiz fast zweieinhalb Wochen vor der Publikation des Beitrags am 29. Oktober 2024. DPD Schweiz ging nicht auf das Angebot ein und nahm nicht vor der Kamera Stellung. Schlussendlich \u00e4usserte sich das Unternehmen schriftlich.\u00a0<\/div><div>\u00a0<\/div><div>Wir hielten uns bei diesem Beitrag an die Publizistischen Leitlinien von SRF, wonach wir sachgerecht, vielf\u00e4ltig und unabh\u00e4ngig berichten. DPD Schweiz konnte zu den wesentlichen Punkten (Best Arguments) Stellung nehmen.<\/div><div>\u00a0<\/div><div>Diese Haltung von DPD unterstreicht, warum unser Engagement so wichtig ist.<\/div><div>\u00a0<\/div><div><strong>Ein symbolischer Akt: \u00dcbergabe per Velokurierin<\/strong><\/div><div>Um die Unterschriften dennoch zu \u00fcberbringen, haben wir sie am Dienstag, 10. Dezember symbolisch per Velokurierin an den Hauptsitz von DPD gesendet. Mit dieser Aktion haben wir gezeigt, dass wir uns nicht abwimmeln lassen und weiter Druck machen werden, bis sich die Arbeitsbedingungen bei DPD grundlegend verbessern.<\/div><div>\u00a0<\/div><div><strong>Unser gemeinsamer Erfolg<\/strong><\/div><div>Die Kampagne hat nicht nur das Bewusstsein f\u00fcr die Missst\u00e4nde bei DPD gesch\u00e4rft, sondern auch gezeigt, dass wir gemeinsam stark sind. Die Unterst\u00fctzung aus der Community und die Bereitschaft, aktiv zu handeln, haben diesen Einsatz m\u00f6glich gemacht. Doch der Kampf f\u00fcr faire Arbeitsbedingungen ist noch nicht vorbei. Mit der Hilfe unserer Community k\u00f6nnen wir weiterhin den Finger in die Wunde legen und Unternehmen wie DPD zur Verantwortung ziehen.<\/div><div>\u00a0<\/div><div>Danke f\u00fcr die Unterst\u00fctzung und Solidarit\u00e4t! Gemeinsam machen wir den M\u00e4chtigen ihr schmutziges Gesch\u00e4ft schwer!<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f260b9c narrow elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f260b9c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-481aa3b6\" data-id=\"481aa3b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2040142 elementor-widget elementor-widget-spacer\" data-id=\"2040142\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5aa5d734 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5aa5d734\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/campax.org\/widerstand\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">F\u00fcr Campax spenden<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Die Kampagne f\u00fcr faire Arbeitsbedingungen bei DPD begann mit einem ersch\u00fctternden Bericht des Schweizer Fernsehens (SRF). Der Artikel deckte auf, dass die Arbeitsbedingungen f\u00fcr viele Fahrer*innen bei DPD miserabel sind. Extreme Arbeitszeiten, unzumutbare Lasten und die fehlende direkte Anstellung bei DPD selbst machen die Situation f\u00fcr viele untragbar. Stattdessen l\u00e4sst das Unternehmen Zusteller*innen \u00fcber Subunternehmer [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":59078,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[26,8],"tags":[],"class_list":["post-59082","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-act","category-news"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-12-09 08:43:37","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/campax.org\/de\/wp-json\/wp\/v2\/posts\/59082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campax.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/campax.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/campax.org\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/campax.org\/de\/wp-json\/wp\/v2\/comments?post=59082"}],"version-history":[{"count":0,"href":"https:\/\/campax.org\/de\/wp-json\/wp\/v2\/posts\/59082\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/campax.org\/de\/wp-json\/wp\/v2\/media\/59078"}],"wp:attachment":[{"href":"https:\/\/campax.org\/de\/wp-json\/wp\/v2\/media?parent=59082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/campax.org\/de\/wp-json\/wp\/v2\/categories?post=59082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/campax.org\/de\/wp-json\/wp\/v2\/tags?post=59082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}