{"id":37410,"date":"2023-07-04T10:09:50","date_gmt":"2023-07-04T09:09:50","guid":{"rendered":"https:\/\/campax.org\/?p=37410"},"modified":"2023-07-04T12:58:49","modified_gmt":"2023-07-04T11:58:49","slug":"der-14-juni-war-laut-jetzt-erst-recht","status":"publish","type":"post","link":"https:\/\/campax.org\/de\/der-14-juni-war-laut-jetzt-erst-recht\/","title":{"rendered":"Der 14. Juni war laut \u2013 jetzt erst recht!"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"37410\" class=\"elementor elementor-37410\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51b373d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"51b373d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a9dec17\" data-id=\"a9dec17\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a73bcd elementor-widget elementor-widget-heading\" data-id=\"2a73bcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Der 14. Juni war laut \u2013 jetzt m\u00fcssen wir weiterk\u00e4mpfen!<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b778142 elementor-widget elementor-widget-text-editor\" data-id=\"b778142\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Jeder Tag muss 14. Juni sein, denn Sexismus und Diskriminierung sind unser Alltag! Damit unsere Politik endlich vorw\u00e4rts macht, brauchen wir mehr Repr\u00e4sentation, mehr feministische Personen im Parlament. Im Herbst k\u00f6nnen wir das gemeinsam \u00e4ndern. Unterzeichne jetzt unser feministisches Wahlversprechen und nutze Deine Stimme f\u00fcr Gleichstellung!<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfb2172 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"dfb2172\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/campax.org\/wahlen-2023-gleichstellung-jetzt\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt f\u00fcr Gleichstellung unterzeichnen!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b28726 elementor-widget elementor-widget-text-editor\" data-id=\"3b28726\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><em>\u201cIch bin h\u00e4ssig, weil die Schweiz immer noch nur zwei Geschlechter kennt!\u201d<\/em><br \/><em>\u201cIch streike, weil ich eine anst\u00e4ndige Rente will!\u201d<\/em><br \/><em>\u201cIch bin h\u00e4ssig, weil unsere K\u00f6rper nicht uns geh\u00f6ren!\u201d<\/em><br \/><em>\u201cIch streike, weil migrantische Frauen Mehrfachdiskriminierung erfahren und aus der Gesellschaft ausgeschlossen werden!\u201d<\/em><\/h5><p>Diese und noch viel mehr Streikgr\u00fcnde hallten am 14. Juni durch die Strassen in der Schweiz. Hunderttausende FINTA*-Personen (Frauen, intergeschlechtliche, nonbin\u00e4re, trans und agender Personen) haben sich versammelt und gemeinsam gegen das Patriarchat demonstriert! Bezahlbare Kinderbetreuung, ein politisches Mitspracherecht f\u00fcr migrantische Personen, Renten, die zum Leben reichen, Schutz vor sexualisierter Gewalt, das Recht auf Abtreibung sind nur ein Teil der Forderungen, die der feministische Streik gestern durch die Strassen getragen hat. Diese Forderungen m\u00fcssen wir nun ins Parlament bringen.<\/p><p>\u00a0<\/p><p>Vor genau 4 Jahren fand der Frauenstreik 2019 statt, wo viele \u00e4hnliche Forderungen bereits gestellt wurden. Doch in den folgenden 4 Jahren hat sich in der Politik zu wenig bewegt. Im Gegenteil: trans Personen sind unter Beschuss, das Recht auf Abtreibungen wird von SVP-Initiativen angegriffen und unsere Renten wurden verschlechtert.<\/p><p>\u00a0<\/p><p>Deshalb muss unsere violette Welle weiterziehen und im Herbst die Wahlen \u00fcberschwemmen! Wir brauchen feministische Personen im Parlament: FINTA*-Personen, People of Colour, migrantische Personen, behinderte Menschen. Denn nur mit feministischer Repr\u00e4sentation werden unsere Anliegen auch in der Politik behandelt und ernst genommen!<\/p><p>\u00a0<\/p><p>Damit dies Realit\u00e4t wird, m\u00fcssen wir jetzt f\u00fcr feministische Wahlen mobilisieren. Der erste Schritt dieser Mobilisierung ist ein Wahlversprechen \u2013 ein Signal nach aussen: Wir sind viele und wir w\u00e4hlen feministisch!<br \/>Nutze jetzt Deine Stimme und versprich, feministisch zu w\u00e4hlen!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d81577 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"2d81577\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/campax.org\/wahlen-2023-gleichstellung-jetzt\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Nutze jetzt Deine Stimme f\u00fcr Gleichstellung!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3f5b90 elementor-widget elementor-widget-gallery\" data-id=\"f3f5b90\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;gallery_layout&quot;:&quot;masonry&quot;,&quot;columns&quot;:3,&quot;link_to&quot;:&quot;custom&quot;,&quot;url&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/flic.kr\\\/s\\\/aHBqjAHL8V&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;lazyload&quot;:&quot;yes&quot;,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/flic.kr\/s\/aHBqjAHL8V\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/campax.org\/wp-content\/uploads\/2023\/07\/52974083376_06062a18af_b.jpg\" data-width=\"684\" data-height=\"1024\" aria-label=\"Campax beim Feministischen Frauenstreik in Bern am 14. Juni 2023\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/flic.kr\/s\/aHBqjAHL8V\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/campax.org\/wp-content\/uploads\/2023\/07\/52974226619_6b5740e29d_b.jpg\" data-width=\"684\" data-height=\"1024\" aria-label=\"Campax beim Feministischen Frauenstreik in Bern am 14. Juni 2023\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/flic.kr\/s\/aHBqjAHL8V\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/campax.org\/wp-content\/uploads\/2023\/07\/52974227939_61998cfbe6_b-768x513.jpg\" data-width=\"768\" data-height=\"513\" aria-label=\"Campax beim Feministischen Frauenstreik in Bern am 14. Juni 2023\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/flic.kr\/s\/aHBqjAHL8V\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/campax.org\/wp-content\/uploads\/2023\/07\/52974454725_390d83ae36_b-768x513.jpg\" data-width=\"768\" data-height=\"513\" aria-label=\"Campax beim Feministischen Frauenstreik in Bern am 14. Juni 2023 (Rede von Itziar Mara\u00f1on, Co-Gesch\u00e4ftsleiterin Campax)\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/flic.kr\/s\/aHBqjAHL8V\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/campax.org\/wp-content\/uploads\/2023\/07\/52975378392_7b215be563_b.jpg\" data-width=\"684\" data-height=\"1024\" aria-label=\"Campax beim Feministischen Frauenstreik in Bern am 14. Juni 2023\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/flic.kr\/s\/aHBqjAHL8V\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/campax.org\/wp-content\/uploads\/2023\/07\/52976124804_d0ddc2078f_b-768x513.jpg\" data-width=\"768\" data-height=\"513\" aria-label=\"Campax beim Feministischen Frauenstreik in Bern am 14. Juni 2023\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/flic.kr\/s\/aHBqjAHL8V\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/campax.org\/wp-content\/uploads\/2023\/07\/52974084141_264a8703c0_b-768x513.jpg\" data-width=\"768\" data-height=\"513\" aria-label=\"Campax beim Feministischen Frauenstreik in Bern am 14. Juni 2023\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/flic.kr\/s\/aHBqjAHL8V\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/campax.org\/wp-content\/uploads\/2023\/07\/52974226029_875d3e1a9b_b-768x513.jpg\" data-width=\"768\" data-height=\"513\" aria-label=\"Campax beim Feministischen Frauenstreik in Bern am 14. Juni 2023\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/flic.kr\/s\/aHBqjAHL8V\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/campax.org\/wp-content\/uploads\/2023\/07\/52974044228_1e58011d06_k-768x1024.jpg\" data-width=\"768\" data-height=\"1024\" aria-label=\"Campax beim Feministischen Frauenstreik in Bern am 14. Juni 2023\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c4de71 elementor-widget elementor-widget-text-editor\" data-id=\"0c4de71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir waren mit einem Campax-Stand in Bern und haben unsere letzten Bauchtaschen unter die Leute gebracht. Danke f\u00fcr diesen wundersch\u00f6nen Tag, an dem wir alle unsere feministische Energie auftanken konnten!\ud83d\udc9c<\/p><p>\u00a0<\/p><p>Jetzt mit Vollgas weiter f\u00fcr die Wahlen, damit unsere Forderungen Realit\u00e4t werden!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee43854 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"ee43854\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/donate.campax.org\/de\/pay?cid=aed29848\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">F\u00fcr die Kampagne spenden<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Der 14. Juni war laut \u2013 jetzt m\u00fcssen wir weiterk\u00e4mpfen! Jeder Tag muss 14. Juni sein, denn Sexismus und Diskriminierung sind unser Alltag! Damit unsere Politik endlich vorw\u00e4rts macht, brauchen wir mehr Repr\u00e4sentation, mehr feministische Personen im Parlament. Im Herbst k\u00f6nnen wir das gemeinsam \u00e4ndern. Unterzeichne jetzt unser feministisches Wahlversprechen und nutze Deine Stimme f\u00fcr [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":37421,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[25,17],"tags":[],"class_list":["post-37410","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-campax","category-gleichstellung"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-12-09 11:53:25","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/campax.org\/de\/wp-json\/wp\/v2\/posts\/37410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campax.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/campax.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/campax.org\/de\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/campax.org\/de\/wp-json\/wp\/v2\/comments?post=37410"}],"version-history":[{"count":0,"href":"https:\/\/campax.org\/de\/wp-json\/wp\/v2\/posts\/37410\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/campax.org\/de\/wp-json\/wp\/v2\/media\/37421"}],"wp:attachment":[{"href":"https:\/\/campax.org\/de\/wp-json\/wp\/v2\/media?parent=37410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/campax.org\/de\/wp-json\/wp\/v2\/categories?post=37410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/campax.org\/de\/wp-json\/wp\/v2\/tags?post=37410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}